{"id":50773,"date":"2014-10-16T00:00:00","date_gmt":"2014-10-16T05:00:00","guid":{"rendered":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/"},"modified":"2022-09-02T20:10:14","modified_gmt":"2022-09-03T01:10:14","slug":"nebraska-scifest-seeks-experts-2","status":"publish","type":"post","link":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/","title":{"rendered":"Nebraska Scifest seeks experts"},"content":{"rendered":"<div class=\"panel body-content\"><div class=\"panel__container\"><p><a href=\"https:\/\/www.unmc.edu\/newsroom\/2014\/05\/12\/science-rocks\/\">The Nebraska Science Festival<\/a> is looking for dynamic and dedicated UNMC experts to share their excitement about science with students in middle school classes and afterschool programs during the 2015 festival.<\/p>\n<div class=\"callout-right\">\n<h3>New newsletter<\/h3>\n<p>NE SciFest has launched a quarterly e-newsletter. Stay up to date on keynote speaker information, registration announcements, contests and more! To subscribe, send an <a href=\"mailto:nescifest@gmail.com\">email<\/a>. <\/p>\n<\/div>\n<p>The third annual event will be held April 10-18, 2015, in Omaha and across the state. UNMC experts available that week would visit Nebraska schools through the Festival&#8217;s Invite-a-Scientist program. The goal of each visit is to inspire middle-schoolers to consider science as a career and to understand how science impacts their lives. <\/p>\n<p>For more information on participating in the inaugural Invite-a-Scientist program, please e-mail <a href=\"mailto:kgerard@unmc.edu\">Kacie Gerard<\/a>. For more information on the Nebraska Science Festival, click  <a href=\"http:\/\/www.nescifest.com\">here<\/a>.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>UNMC experts can share their excitement about science with students.<\/p>\n","protected":false},"author":27,"featured_media":50326,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-50773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","department-unmc-today-todays-headlines","author_override-kacie-gerard-unmc-public-relations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nebraska Scifest seeks experts<\/title>\n<meta name=\"description\" content=\"UNMC experts can share their excitement about science with students.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nebraska Scifest seeks experts\" \/>\n<meta property=\"og:description\" content=\"UNMC experts can share their excitement about science with students.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsroom\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unmcedu\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-16T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-03T01:10:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2014\/09\/Sci30909.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"705\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"John Keenan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unmc\" \/>\n<meta name=\"twitter:site\" content=\"@unmc\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Keenan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/\"},\"author\":{\"name\":\"John Keenan\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#\\\/schema\\\/person\\\/22aaa97fc8a965e5fb8555e8ecb753f5\"},\"headline\":\"Nebraska Scifest seeks experts\",\"datePublished\":\"2014-10-16T05:00:00+00:00\",\"dateModified\":\"2022-09-03T01:10:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Sci30909.gif\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/\",\"url\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/\",\"name\":\"Nebraska Scifest seeks experts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Sci30909.gif\",\"datePublished\":\"2014-10-16T05:00:00+00:00\",\"dateModified\":\"2022-09-03T01:10:14+00:00\",\"description\":\"UNMC experts can share their excitement about science with students.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Sci30909.gif\",\"contentUrl\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Sci30909.gif\",\"width\":705,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/2014\\\/10\\\/16\\\/nebraska-scifest-seeks-experts-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nebraska Scifest seeks experts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#website\",\"url\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/\",\"name\":\"Newsroom\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#organization\",\"name\":\"University of Nebraska Medical Center\",\"url\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/overview-1.png\",\"contentUrl\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/overview-1.png\",\"width\":500,\"height\":153,\"caption\":\"University of Nebraska Medical Center\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/unmcedu\",\"https:\\\/\\\/x.com\\\/unmc\",\"https:\\\/\\\/instagram.com\\\/iamunmc\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UNMCEDU\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/#\\\/schema\\\/person\\\/22aaa97fc8a965e5fb8555e8ecb753f5\",\"name\":\"John Keenan\",\"url\":\"https:\\\/\\\/www.unmc.edu\\\/newsroom\\\/author\\\/02e74f10e0327ad868d138f2b4fdd6f0\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nebraska Scifest seeks experts","description":"UNMC experts can share their excitement about science with students.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/","og_locale":"en_US","og_type":"article","og_title":"Nebraska Scifest seeks experts","og_description":"UNMC experts can share their excitement about science with students.","og_url":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/","og_site_name":"Newsroom","article_publisher":"https:\/\/www.facebook.com\/unmcedu","article_published_time":"2014-10-16T05:00:00+00:00","article_modified_time":"2022-09-03T01:10:14+00:00","og_image":[{"width":705,"height":406,"url":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2014\/09\/Sci30909.gif","type":"image\/gif"}],"author":"John Keenan","twitter_card":"summary_large_image","twitter_creator":"@unmc","twitter_site":"@unmc","twitter_misc":{"Written by":"John Keenan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#article","isPartOf":{"@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/"},"author":{"name":"John Keenan","@id":"https:\/\/www.unmc.edu\/newsroom\/#\/schema\/person\/22aaa97fc8a965e5fb8555e8ecb753f5"},"headline":"Nebraska Scifest seeks experts","datePublished":"2014-10-16T05:00:00+00:00","dateModified":"2022-09-03T01:10:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/www.unmc.edu\/newsroom\/#organization"},"image":{"@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2014\/09\/Sci30909.gif","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/","url":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/","name":"Nebraska Scifest seeks experts","isPartOf":{"@id":"https:\/\/www.unmc.edu\/newsroom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#primaryimage"},"image":{"@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2014\/09\/Sci30909.gif","datePublished":"2014-10-16T05:00:00+00:00","dateModified":"2022-09-03T01:10:14+00:00","description":"UNMC experts can share their excitement about science with students.","breadcrumb":{"@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#primaryimage","url":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2014\/09\/Sci30909.gif","contentUrl":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2014\/09\/Sci30909.gif","width":705,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.unmc.edu\/newsroom\/2014\/10\/16\/nebraska-scifest-seeks-experts-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unmc.edu\/newsroom\/"},{"@type":"ListItem","position":2,"name":"Nebraska Scifest seeks experts"}]},{"@type":"WebSite","@id":"https:\/\/www.unmc.edu\/newsroom\/#website","url":"https:\/\/www.unmc.edu\/newsroom\/","name":"Newsroom","description":"","publisher":{"@id":"https:\/\/www.unmc.edu\/newsroom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unmc.edu\/newsroom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unmc.edu\/newsroom\/#organization","name":"University of Nebraska Medical Center","url":"https:\/\/www.unmc.edu\/newsroom\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unmc.edu\/newsroom\/#\/schema\/logo\/image\/","url":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2022\/08\/overview-1.png","contentUrl":"https:\/\/www.unmc.edu\/newsroom\/wp-content\/uploads\/2022\/08\/overview-1.png","width":500,"height":153,"caption":"University of Nebraska Medical Center"},"image":{"@id":"https:\/\/www.unmc.edu\/newsroom\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unmcedu","https:\/\/x.com\/unmc","https:\/\/instagram.com\/iamunmc","https:\/\/www.youtube.com\/user\/UNMCEDU"]},{"@type":"Person","@id":"https:\/\/www.unmc.edu\/newsroom\/#\/schema\/person\/22aaa97fc8a965e5fb8555e8ecb753f5","name":"John Keenan","url":"https:\/\/www.unmc.edu\/newsroom\/author\/02e74f10e0327ad868d138f2b4fdd6f0\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/posts\/50773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/comments?post=50773"}],"version-history":[{"count":1,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/posts\/50773\/revisions"}],"predecessor-version":[{"id":81129,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/posts\/50773\/revisions\/81129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/media\/50326"}],"wp:attachment":[{"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/media?parent=50773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/categories?post=50773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unmc.edu\/newsroom\/wp-json\/wp\/v2\/tags?post=50773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}